{"id":76,"date":"2020-10-01T10:29:47","date_gmt":"2020-10-01T10:29:47","guid":{"rendered":"https:\/\/festivaldelcentrohistorico.com\/23fch\/?post_type=actividades&#038;p=76"},"modified":"2020-10-14T22:42:21","modified_gmt":"2020-10-14T22:42:21","slug":"un-dia-en-el-museo","status":"publish","type":"actividades","link":"https:\/\/festivaldelcentrohistorico.com\/23fch\/actividades\/un-dia-en-el-museo\/","title":{"rendered":"Un d\u00eda en el Museo &#8211; Museo Radio TGW"},"content":{"rendered":"<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;8 calle 6-72 zona 1, tercer nivel&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:15297,&quot;3&quot;:{&quot;1&quot;:0},&quot;9&quot;:0,&quot;10&quot;:0,&quot;11&quot;:4,&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:2,&quot;2&quot;:1775151},&quot;15&quot;:&quot;Arial&quot;,&quot;16&quot;:9}\">18 calle 6-72 zona 1, tercer nivel<\/span><\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"categories":[8],"acf":[],"_links":{"self":[{"href":"https:\/\/festivaldelcentrohistorico.com\/23fch\/wp-json\/wp\/v2\/actividades\/76"}],"collection":[{"href":"https:\/\/festivaldelcentrohistorico.com\/23fch\/wp-json\/wp\/v2\/actividades"}],"about":[{"href":"https:\/\/festivaldelcentrohistorico.com\/23fch\/wp-json\/wp\/v2\/types\/actividades"}],"wp:attachment":[{"href":"https:\/\/festivaldelcentrohistorico.com\/23fch\/wp-json\/wp\/v2\/media?parent=76"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/festivaldelcentrohistorico.com\/23fch\/wp-json\/wp\/v2\/categories?post=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}