{"id":256,"date":"2020-10-10T14:26:33","date_gmt":"2020-10-10T14:26:33","guid":{"rendered":"https:\/\/festivaldelcentrohistorico.com\/23fch\/?post_type=actividades&#038;p=256"},"modified":"2020-10-10T14:36:08","modified_gmt":"2020-10-10T14:36:08","slug":"obra-virtual-de-panchorizo","status":"publish","type":"actividades","link":"https:\/\/festivaldelcentrohistorico.com\/23fch\/actividades\/obra-virtual-de-panchorizo\/","title":{"rendered":"Obra virtual de Panchorizo"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":[],"categories":[12],"acf":[],"_links":{"self":[{"href":"https:\/\/festivaldelcentrohistorico.com\/23fch\/wp-json\/wp\/v2\/actividades\/256"}],"collection":[{"href":"https:\/\/festivaldelcentrohistorico.com\/23fch\/wp-json\/wp\/v2\/actividades"}],"about":[{"href":"https:\/\/festivaldelcentrohistorico.com\/23fch\/wp-json\/wp\/v2\/types\/actividades"}],"wp:attachment":[{"href":"https:\/\/festivaldelcentrohistorico.com\/23fch\/wp-json\/wp\/v2\/media?parent=256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/festivaldelcentrohistorico.com\/23fch\/wp-json\/wp\/v2\/categories?post=256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}