{"id":128,"date":"2020-10-01T12:50:51","date_gmt":"2020-10-01T12:50:51","guid":{"rendered":"https:\/\/festivaldelcentrohistorico.com\/23fch\/?post_type=actividades&#038;p=128"},"modified":"2020-10-14T21:56:26","modified_gmt":"2020-10-14T21:56:26","slug":"capsula-historica-barrio-de-santa-rosa","status":"publish","type":"actividades","link":"https:\/\/festivaldelcentrohistorico.com\/23fch\/actividades\/capsula-historica-barrio-de-santa-rosa\/","title":{"rendered":"C\u00e1psula hist\u00f3rica &#8211; Barrio de Santa Rosa"},"content":{"rendered":"<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Casa Municipal Barnoya Garc\u00eda (8\u00aa Calle 10-12 zona 1)&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:15297,&quot;3&quot;:{&quot;1&quot;:0},&quot;9&quot;:0,&quot;10&quot;:0,&quot;11&quot;:4,&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:2,&quot;2&quot;:1775151},&quot;15&quot;:&quot;Arial&quot;,&quot;16&quot;:9}\">Casa Municipal Barnoya Garc\u00eda (8\u00aa Calle 10-12 zona 1)<\/span><\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"categories":[4],"acf":[],"_links":{"self":[{"href":"https:\/\/festivaldelcentrohistorico.com\/23fch\/wp-json\/wp\/v2\/actividades\/128"}],"collection":[{"href":"https:\/\/festivaldelcentrohistorico.com\/23fch\/wp-json\/wp\/v2\/actividades"}],"about":[{"href":"https:\/\/festivaldelcentrohistorico.com\/23fch\/wp-json\/wp\/v2\/types\/actividades"}],"wp:attachment":[{"href":"https:\/\/festivaldelcentrohistorico.com\/23fch\/wp-json\/wp\/v2\/media?parent=128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/festivaldelcentrohistorico.com\/23fch\/wp-json\/wp\/v2\/categories?post=128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}